{"id":6155,"date":"2021-07-12T16:41:40","date_gmt":"2021-07-12T16:41:40","guid":{"rendered":"https:\/\/wideest.ee\/wp-content\/uploads\/2021\/07\/TCC-21.jpg"},"modified":"2022-04-25T09:14:56","modified_gmt":"2022-04-25T09:14:56","slug":"tcc-21-2","status":"inherit","type":"attachment","link":"https:\/\/wideest.ee\/en\/air-suspension\/tcc-21-2\/","title":{"rendered":"TCC-21"},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"class_list":["post-6155","attachment","type-attachment","status-inherit","hentry"],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/wideest.ee\/wp-content\/uploads\/2021\/07\/TCC-21-scaled.jpg'><img decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/wideest.ee\/wp-content\/uploads\/2021\/07\/TCC-21-300x200.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/wideest.ee\/wp-content\/uploads\/2021\/07\/TCC-21-300x200.jpg 300w, https:\/\/wideest.ee\/wp-content\/uploads\/2021\/07\/TCC-21-1024x683.jpg 1024w, https:\/\/wideest.ee\/wp-content\/uploads\/2021\/07\/TCC-21-768x512.jpg 768w, https:\/\/wideest.ee\/wp-content\/uploads\/2021\/07\/TCC-21-1536x1024.jpg 1536w, https:\/\/wideest.ee\/wp-content\/uploads\/2021\/07\/TCC-21-scaled.jpg 2048w, https:\/\/wideest.ee\/wp-content\/uploads\/2021\/07\/TCC-21-1620x1080.jpg 1620w, https:\/\/wideest.ee\/wp-content\/uploads\/2021\/07\/TCC-21-600x400.jpg 600w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":2048,"height":1365,"file":"2021\/07\/TCC-21-scaled.jpg","sizes":{"medium":{"file":"TCC-21-300x200.jpg","width":300,"height":200,"mime_type":"image\/jpeg","source_url":"https:\/\/wideest.ee\/wp-content\/uploads\/2021\/07\/TCC-21-300x200.jpg"},"large":{"file":"TCC-21-1024x683.jpg","width":1024,"height":683,"mime_type":"image\/jpeg","source_url":"https:\/\/wideest.ee\/wp-content\/uploads\/2021\/07\/TCC-21-1024x683.jpg"},"thumbnail":{"file":"TCC-21-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/wideest.ee\/wp-content\/uploads\/2021\/07\/TCC-21-150x150.jpg"},"medium_large":{"file":"TCC-21-768x512.jpg","width":768,"height":512,"mime_type":"image\/jpeg","source_url":"https:\/\/wideest.ee\/wp-content\/uploads\/2021\/07\/TCC-21-768x512.jpg"},"1536x1536":{"file":"TCC-21-1536x1024.jpg","width":1536,"height":1024,"mime_type":"image\/jpeg","source_url":"https:\/\/wideest.ee\/wp-content\/uploads\/2021\/07\/TCC-21-1536x1024.jpg"},"2048x2048":{"file":"TCC-21-2048x1365.jpg","width":2048,"height":1365,"mime_type":"image\/jpeg","source_url":"https:\/\/wideest.ee\/wp-content\/uploads\/2021\/07\/TCC-21-2048x1365.jpg"},"post-thumbnail":{"file":"TCC-21-1024x683.jpg","width":1024,"height":683,"mime_type":"image\/jpeg","source_url":"https:\/\/wideest.ee\/wp-content\/uploads\/2021\/07\/TCC-21-1024x683.jpg"},"mesmerize-full-hd":{"file":"TCC-21-1620x1080.jpg","width":1620,"height":1080,"mime_type":"image\/jpeg","source_url":"https:\/\/wideest.ee\/wp-content\/uploads\/2021\/07\/TCC-21-1620x1080.jpg"},"woocommerce_thumbnail":{"file":"TCC-21-300x300.jpg","width":300,"height":300,"uncropped":"0","mime_type":"image\/jpeg","source_url":"https:\/\/wideest.ee\/wp-content\/uploads\/2021\/07\/TCC-21-300x300.jpg"},"woocommerce_single":{"file":"TCC-21-600x400.jpg","width":600,"height":400,"mime_type":"image\/jpeg","source_url":"https:\/\/wideest.ee\/wp-content\/uploads\/2021\/07\/TCC-21-600x400.jpg"},"woocommerce_gallery_thumbnail":{"file":"TCC-21-100x100.jpg","width":100,"height":100,"mime_type":"image\/jpeg","source_url":"https:\/\/wideest.ee\/wp-content\/uploads\/2021\/07\/TCC-21-100x100.jpg"},"shop_catalog":{"file":"TCC-21-300x300.jpg","width":300,"height":300,"mime_type":"image\/jpeg","source_url":"https:\/\/wideest.ee\/wp-content\/uploads\/2021\/07\/TCC-21-300x300.jpg"},"shop_single":{"file":"TCC-21-600x400.jpg","width":600,"height":400,"mime_type":"image\/jpeg","source_url":"https:\/\/wideest.ee\/wp-content\/uploads\/2021\/07\/TCC-21-600x400.jpg"},"shop_thumbnail":{"file":"TCC-21-100x100.jpg","width":100,"height":100,"mime_type":"image\/jpeg","source_url":"https:\/\/wideest.ee\/wp-content\/uploads\/2021\/07\/TCC-21-100x100.jpg"},"full":{"file":"TCC-21-scaled.jpg","width":2048,"height":1365,"mime_type":"image\/jpeg","source_url":"https:\/\/wideest.ee\/wp-content\/uploads\/2021\/07\/TCC-21-scaled.jpg"}},"image_meta":{"aperture":"4.5","credit":"","camera":"ILCE-7M3","caption":"","created_timestamp":"1621875662","copyright":"","focal_length":"45","iso":"400","shutter_speed":"0.0125","title":"","orientation":"0"},"original_image":"TCC-21.jpg"},"post":6717,"source_url":"https:\/\/wideest.ee\/wp-content\/uploads\/2021\/07\/TCC-21-scaled.jpg","_links":{"self":[{"href":"https:\/\/wideest.ee\/en\/wp-json\/wp\/v2\/media\/6155","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wideest.ee\/en\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/wideest.ee\/en\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/wideest.ee\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/wideest.ee\/en\/wp-json\/wp\/v2\/comments?post=6155"}]}}